{"id":15631,"date":"2021-07-29T17:28:06","date_gmt":"2021-07-29T21:28:06","guid":{"rendered":"https:\/\/intosai.nclud.com\/journal-entry\/sao-georgia-audits-public-debt\/"},"modified":"2023-05-07T23:41:32","modified_gmt":"2023-05-08T03:41:32","slug":"sao-georgia-audits-public-debt","status":"publish","type":"journal-entry","link":"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/","title":{"rendered":"SAO Georgia pr\u00fcft Praktiken der \u00f6ffentlichen Schuldenverwaltung"},"content":{"rendered":"<p>Ein Hauptaugenmerk des State Audit Office (SAO) von Georgien liegt auf der Pr\u00fcfung der Wirksamkeit des \u00f6ffentlichen Schuldenmanagements der Regierung. Zu diesem Zweck f\u00fchrte das SAO Georgien im Jahr 2020 eine Pr\u00fcfung durch, um die Umsetzung seiner Empfehlungen aus dem Jahr 2015 zur Verbesserung der Praktiken der \u00f6ffentlichen Schuldenverwaltung zu verfolgen.<\/p>\n<p>Die Verwaltung der Staatsverschuldung ist von besonderer Bedeutung f\u00fcr die Gew\u00e4hrleistung der finanzpolitischen und makro\u00f6konomischen Stabilit\u00e4t. Wenn Regierungen die Staatsverschuldung effektiv verwalten, dienen die aufgenommenen Mittel als Anreiz f\u00fcr das Wirtschaftswachstum, w\u00e4hrend eine ineffektive Verwaltung zu einer Wirtschaftskrise f\u00fchren kann. W\u00e4hrend der COVID-19-Pandemie, in der die weltweite Verschuldung erheblich gestiegen ist, sind die Risiken im Zusammenhang mit der Tragf\u00e4higkeit der Schulden besonders dringlich geworden.<\/p>\n<p>Die ORKB k\u00f6nnen eine wichtige Rolle bei der Gew\u00e4hrleistung eines soliden und transparenten \u00f6ffentlichen Schuldenmanagements spielen, indem sie unabh\u00e4ngige, qualitativ hochwertige Pr\u00fcfungen der \u00f6ffentlichen Schulden durchf\u00fchren. Diese Grunds\u00e4tze wurden in den Leitlinien f\u00fcr die Pr\u00fcfung der Staatsverschuldung (GUID 5250) dargelegt, die auf dem Internationalen Kongress f\u00fcr Oberste Rechnungskontrollbeh\u00f6rden (INCOSAI) 2020 angenommen wurden.<\/p>\n<p>Die ORKB Georgien ist als aktives Mitglied der INTOSAI-Arbeitsgruppe f\u00fcr Staatsschulden, deren Ziel der Austausch und die Entwicklung von Best Practices f\u00fcr die Verwaltung von Staatsschulden ist, der Ansicht, dass ihre Erfahrungen in diesem Bereich als n\u00fctzliche Fallstudie f\u00fcr andere ORKB dienen k\u00f6nnen.<\/p>\n<p>Die <a href=\"https:\/\/www.sao.ge\/Uploads\/2020\/5\/%E1%83%A1%E1%83%90%E1%83%AE%E1%83%94%E1%83%9A%E1%83%9B%E1%83%AC%E1%83%98%E1%83%A4%E1%83%9D_%E1%83%95%E1%83%90%E1%83%9A%E1%83%98%E1%83%A1_%E1%83%9B%E1%83%90%E1%83%A0%E1%83%97%E1%83%95%E1%83%90.pdf\">Follow-up-Leistungspr\u00fcfung<\/a> des SAO <a href=\"https:\/\/www.sao.ge\/Uploads\/2020\/5\/%E1%83%A1%E1%83%90%E1%83%AE%E1%83%94%E1%83%9A%E1%83%9B%E1%83%AC%E1%83%98%E1%83%A4%E1%83%9D_%E1%83%95%E1%83%90%E1%83%9A%E1%83%98%E1%83%A1_%E1%83%9B%E1%83%90%E1%83%A0%E1%83%97%E1%83%95%E1%83%90.pdf\">zur Verwaltung der Staatsschulden<\/a> ergab, dass sich die Staatsverschuldung Georgiens von 2014 bis 2019 verdoppelt hat und Ende Oktober 2019 42 Prozent des prognostizierten Bruttoinlandsprodukts (BIP) betragen wird. Achtundsiebzig Prozent der gesamten Staatsverschuldung waren damals extern, d.h. sie wurden von internationalen Finanzinstitutionen oder bilateralen Gl\u00e4ubigern in Fremdw\u00e4hrung aufgenommen.<\/p>\n<p>Dieser Anstieg der Staatsverschuldung wurde durch eine erh\u00f6hte Kreditaufnahme und die Abwertung der Landesw\u00e4hrung verursacht. Die \u00f6ffentliche Schuldenquote stieg infolge der Pandemie weiter an und wird Ende 2020 voraussichtlich 57,9 % des BIP betragen.<\/p>\n<p>Die Pr\u00fcfung des SAO Georgien f\u00fcr das Jahr 2020 ergab au\u00dferdem, dass die Regierung zwar einige positive Schritte zur Verwaltung der Staatsschulden unternommen, aber nur vier der neun Empfehlungen des SAO umgesetzt hatte. Das SAO stellte die folgenden M\u00e4ngel fest:<\/p>\n<p><em><strong>Die Definition der Staatsverschuldung war unvollst\u00e4ndig und entsprach nicht den internationalen Standards.<\/strong><\/em>  Die Verschuldungsgrenzen des \u00f6ffentlichen Sektors in Georgien werden durch zwei verschiedene Gesetze festgelegt, von denen die Regierung das eine zur Berechnung der j\u00e4hrlichen Verschuldungsgrenze und das andere zur Berechnung der Schuldenregel heranzieht. Diese unterschiedlichen Grenzwerte stehen nicht im Einklang mit dem <a href=\"https:\/\/www.imf.org\/external\/Pubs\/FT\/GFS\/Manual\/2014\/gfsfinal.pdf\">Government Finance Statistics Manual<\/a> des Internationalen W\u00e4hrungsfonds (GFSM 2014).<\/p>\n<p><em><strong>Eventualverbindlichkeiten wurden in den Haushaltsunterlagen nicht dargestellt.<\/strong><\/em>  Eventualverbindlichkeiten sind f\u00fcr die Zwecke der Erstellung von Statistiken \u00fcber die \u00f6ffentlichen Finanzen nicht gesetzlich definiert. Folglich ber\u00fccksichtigte die Regierung bei der Aufstellung ihres Haushaltsplans nicht das Gesamtvolumen der Eventualverbindlichkeiten.<\/p>\n<p>Das SAO wies die Regierung auf die potenziellen Risiken hin, die sich aus dieser Frage f\u00fcr die Rentenagentur und die Einlagensicherungsagentur ergeben. So ist der Staat im Falle der Liquidation, der Insolvenz oder des Konkurses einer Gesch\u00e4ftsbank verpflichtet, jedem betroffenen Einleger bis zu 15.000 GEL (fast 5.000 US-Dollar oder rund 4.000 Euro) zu erstatten.<\/p>\n<p><em><strong>Die Regierung hatte die Aufgaben und Zust\u00e4ndigkeiten der verschiedenen Parteien bei der Ermittlung des Kreditbedarfs nicht festgelegt.<\/strong><\/em>  Die Regierung verf\u00fcgte \u00fcber keinen formellen Leitfaden oder eine Methodik, in der die Aufgaben, Zust\u00e4ndigkeiten oder Struktureinheiten beschrieben waren, die an der Ermittlung des Bedarfs an Nettokrediten in der Haushaltsplanungsphase beteiligt sind. Diese Art von Dokument ist von entscheidender Bedeutung, um die Transparenz, Kontinuit\u00e4t und Verantwortlichkeit des Prozesses zu gew\u00e4hrleisten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Hauptaugenmerk des State Audit Office (SAO) von Georgien liegt auf der Pr\u00fcfung der Wirksamkeit des \u00f6ffentlichen Schuldenmanagements der Regierung. Zu diesem Zweck f\u00fchrte das SAO Georgia im Jahr 2020 eine Pr\u00fcfung durch, um die&#8230;<\/p>\n","protected":false},"author":89,"featured_media":7564,"template":"","meta":{"_acf_changed":false,"footnotes":""},"journal-categories":[2508,2563],"content-tags":[2168],"country":[2867],"region":[2597],"section":[2659],"coauthors":[],"class_list":["post-15631","journal-entry","type-journal-entry","status-publish","has-post-thumbnail","hentry","journal-categories-kurzmeldungen","journal-categories-sommer-2021","content-tags-prufung-der-staatsverschuldung","country-georgia-de","region-eurosai-de","section-kurzmeldungen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SAO Georgia pr\u00fcft Praktiken der \u00f6ffentlichen Schuldenverwaltung - INTOSAI Journal<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SAO Georgia pr\u00fcft Praktiken der \u00f6ffentlichen Schuldenverwaltung - INTOSAI Journal\" \/>\n<meta property=\"og:description\" content=\"Ein Hauptaugenmerk des State Audit Office (SAO) von Georgien liegt auf der Pr\u00fcfung der Wirksamkeit des \u00f6ffentlichen Schuldenmanagements der Regierung. Zu diesem Zweck f\u00fchrte das SAO Georgia im Jahr 2020 eine Pr\u00fcfung durch, um die...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/\" \/>\n<meta property=\"og:site_name\" content=\"INTOSAI Journal\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-08T03:41:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/02\/SAO-Georgia-logo-for-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"221\" \/>\n\t<meta property=\"og:image:height\" content=\"221\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@intosaijournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"State Audit Office of Georgia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/\",\"url\":\"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/\",\"name\":\"SAO Georgia pr\u00fcft Praktiken der \u00f6ffentlichen Schuldenverwaltung - INTOSAI Journal\",\"isPartOf\":{\"@id\":\"https:\/\/intosai.nclud.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/02\/SAO-Georgia-logo-for-web.jpg\",\"datePublished\":\"2021-07-29T21:28:06+00:00\",\"dateModified\":\"2023-05-08T03:41:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/#primaryimage\",\"url\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/02\/SAO-Georgia-logo-for-web.jpg\",\"contentUrl\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/02\/SAO-Georgia-logo-for-web.jpg\",\"width\":221,\"height\":221},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/intosai.nclud.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SAO Georgia pr\u00fcft Praktiken der \u00f6ffentlichen Schuldenverwaltung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/intosai.nclud.com\/#website\",\"url\":\"https:\/\/intosai.nclud.com\/\",\"name\":\"INTOSAI Journal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/intosai.nclud.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/intosai.nclud.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/intosai.nclud.com\/#organization\",\"name\":\"INTOSAI Journal\",\"url\":\"https:\/\/intosai.nclud.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/intosai.nclud.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":736,\"height\":122,\"caption\":\"INTOSAI Journal\"},\"image\":{\"@id\":\"https:\/\/intosai.nclud.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/intosaijournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SAO Georgia pr\u00fcft Praktiken der \u00f6ffentlichen Schuldenverwaltung - INTOSAI Journal","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"SAO Georgia pr\u00fcft Praktiken der \u00f6ffentlichen Schuldenverwaltung - INTOSAI Journal","og_description":"Ein Hauptaugenmerk des State Audit Office (SAO) von Georgien liegt auf der Pr\u00fcfung der Wirksamkeit des \u00f6ffentlichen Schuldenmanagements der Regierung. Zu diesem Zweck f\u00fchrte das SAO Georgia im Jahr 2020 eine Pr\u00fcfung durch, um die...","og_url":"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/","og_site_name":"INTOSAI Journal","article_modified_time":"2023-05-08T03:41:32+00:00","og_image":[{"width":221,"height":221,"url":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/02\/SAO-Georgia-logo-for-web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@intosaijournal","twitter_misc":{"Est. reading time":"3 minutes","Written by":"State Audit Office of Georgia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/","url":"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/","name":"SAO Georgia pr\u00fcft Praktiken der \u00f6ffentlichen Schuldenverwaltung - INTOSAI Journal","isPartOf":{"@id":"https:\/\/intosai.nclud.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/#primaryimage"},"image":{"@id":"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/#primaryimage"},"thumbnailUrl":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/02\/SAO-Georgia-logo-for-web.jpg","datePublished":"2021-07-29T21:28:06+00:00","dateModified":"2023-05-08T03:41:32+00:00","breadcrumb":{"@id":"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/#primaryimage","url":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/02\/SAO-Georgia-logo-for-web.jpg","contentUrl":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/02\/SAO-Georgia-logo-for-web.jpg","width":221,"height":221},{"@type":"BreadcrumbList","@id":"https:\/\/intosai.nclud.com\/de\/journal-entry\/sao-georgia-audits-public-debt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intosai.nclud.com\/de\/"},{"@type":"ListItem","position":2,"name":"SAO Georgia pr\u00fcft Praktiken der \u00f6ffentlichen Schuldenverwaltung"}]},{"@type":"WebSite","@id":"https:\/\/intosai.nclud.com\/#website","url":"https:\/\/intosai.nclud.com\/","name":"INTOSAI Journal","description":"","publisher":{"@id":"https:\/\/intosai.nclud.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intosai.nclud.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/intosai.nclud.com\/#organization","name":"INTOSAI Journal","url":"https:\/\/intosai.nclud.com\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/intosai.nclud.com\/#\/schema\/logo\/image\/","url":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","width":736,"height":122,"caption":"INTOSAI Journal"},"image":{"@id":"https:\/\/intosai.nclud.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/intosaijournal"]}]}},"_links":{"self":[{"href":"https:\/\/intosai.nclud.com\/de\/wp-json\/wp\/v2\/journal-entry\/15631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intosai.nclud.com\/de\/wp-json\/wp\/v2\/journal-entry"}],"about":[{"href":"https:\/\/intosai.nclud.com\/de\/wp-json\/wp\/v2\/types\/journal-entry"}],"author":[{"embeddable":true,"href":"https:\/\/intosai.nclud.com\/de\/wp-json\/wp\/v2\/users\/89"}],"version-history":[{"count":1,"href":"https:\/\/intosai.nclud.com\/de\/wp-json\/wp\/v2\/journal-entry\/15631\/revisions"}],"predecessor-version":[{"id":15635,"href":"https:\/\/intosai.nclud.com\/de\/wp-json\/wp\/v2\/journal-entry\/15631\/revisions\/15635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intosai.nclud.com\/de\/wp-json\/wp\/v2\/media\/7564"}],"wp:attachment":[{"href":"https:\/\/intosai.nclud.com\/de\/wp-json\/wp\/v2\/media?parent=15631"}],"wp:term":[{"taxonomy":"journal-categories","embeddable":true,"href":"https:\/\/intosai.nclud.com\/de\/wp-json\/wp\/v2\/journal-categories?post=15631"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/intosai.nclud.com\/de\/wp-json\/wp\/v2\/content-tags?post=15631"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/intosai.nclud.com\/de\/wp-json\/wp\/v2\/country?post=15631"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/intosai.nclud.com\/de\/wp-json\/wp\/v2\/region?post=15631"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/intosai.nclud.com\/de\/wp-json\/wp\/v2\/section?post=15631"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/intosai.nclud.com\/de\/wp-json\/wp\/v2\/coauthors?post=15631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}